{"id":1773,"date":"2017-11-24T23:00:48","date_gmt":"2017-11-24T22:00:48","guid":{"rendered":"http:\/\/actaxlaw.com\/careers-posizioni-aperte\/"},"modified":"2019-01-22T22:02:46","modified_gmt":"2019-01-22T21:02:46","slug":"kaifanggangwei","status":"publish","type":"page","link":"https:\/\/actaxlaw.com\/zh-hans\/kaifanggangwei\/","title":{"rendered":"\u5f00\u653e\u5c97\u4f4d"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-careers-posizioni.php","meta":{"_acf_changed":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-1773","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u5f00\u653e\u5c97\u4f4d<\/title>\n<meta name=\"description\" content=\"Scopri qui se \u00e8 disponibile una posizione per il tuo profilo professionale e inizia a lavorare con uno dei maggiori studi legali e tributari milanesi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/actaxlaw.com\/zh-hans\/kaifanggangwei\/\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u5f00\u653e\u5c97\u4f4d\" \/>\n<meta property=\"og:description\" content=\"Scopri qui se \u00e8 disponibile una posizione per il tuo profilo professionale e inizia a lavorare con uno dei maggiori studi legali e tributari milanesi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/actaxlaw.com\/zh-hans\/kaifanggangwei\/\" \/>\n<meta property=\"og:site_name\" content=\"Ac Avvocati\" \/>\n<meta property=\"article:modified_time\" content=\"2019-01-22T21:02:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/actaxlaw.com\\\/zh-hans\\\/kaifanggangwei\\\/\",\"url\":\"https:\\\/\\\/actaxlaw.com\\\/zh-hans\\\/kaifanggangwei\\\/\",\"name\":\"\u5f00\u653e\u5c97\u4f4d\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/actaxlaw.com\\\/zh-hans\\\/#website\"},\"datePublished\":\"2017-11-24T22:00:48+00:00\",\"dateModified\":\"2019-01-22T21:02:46+00:00\",\"description\":\"Scopri qui se \u00e8 disponibile una posizione per il tuo profilo professionale e inizia a lavorare con uno dei maggiori studi legali e tributari milanesi.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/actaxlaw.com\\\/zh-hans\\\/kaifanggangwei\\\/#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/actaxlaw.com\\\/zh-hans\\\/kaifanggangwei\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/actaxlaw.com\\\/zh-hans\\\/kaifanggangwei\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/actaxlaw.com\\\/zh-hans\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u5f00\u653e\u5c97\u4f4d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/actaxlaw.com\\\/zh-hans\\\/#website\",\"url\":\"https:\\\/\\\/actaxlaw.com\\\/zh-hans\\\/\",\"name\":\"Ac Avvocati\",\"description\":\"Avvocati e Commercialisti\",\"publisher\":{\"@id\":\"https:\\\/\\\/actaxlaw.com\\\/zh-hans\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/actaxlaw.com\\\/zh-hans\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/actaxlaw.com\\\/zh-hans\\\/#organization\",\"name\":\"Ac Avvocati\",\"url\":\"https:\\\/\\\/actaxlaw.com\\\/zh-hans\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\\\/\\\/actaxlaw.com\\\/zh-hans\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/actaxlaw.com\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/AC-logo-1.png\",\"contentUrl\":\"https:\\\/\\\/actaxlaw.com\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/AC-logo-1.png\",\"width\":88,\"height\":91,\"caption\":\"Ac Avvocati\"},\"image\":{\"@id\":\"https:\\\/\\\/actaxlaw.com\\\/zh-hans\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u5f00\u653e\u5c97\u4f4d","description":"Scopri qui se \u00e8 disponibile una posizione per il tuo profilo professionale e inizia a lavorare con uno dei maggiori studi legali e tributari milanesi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/actaxlaw.com\/zh-hans\/kaifanggangwei\/","og_locale":"zh_CN","og_type":"article","og_title":"\u5f00\u653e\u5c97\u4f4d","og_description":"Scopri qui se \u00e8 disponibile una posizione per il tuo profilo professionale e inizia a lavorare con uno dei maggiori studi legali e tributari milanesi.","og_url":"https:\/\/actaxlaw.com\/zh-hans\/kaifanggangwei\/","og_site_name":"Ac Avvocati","article_modified_time":"2019-01-22T21:02:46+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/actaxlaw.com\/zh-hans\/kaifanggangwei\/","url":"https:\/\/actaxlaw.com\/zh-hans\/kaifanggangwei\/","name":"\u5f00\u653e\u5c97\u4f4d","isPartOf":{"@id":"https:\/\/actaxlaw.com\/zh-hans\/#website"},"datePublished":"2017-11-24T22:00:48+00:00","dateModified":"2019-01-22T21:02:46+00:00","description":"Scopri qui se \u00e8 disponibile una posizione per il tuo profilo professionale e inizia a lavorare con uno dei maggiori studi legali e tributari milanesi.","breadcrumb":{"@id":"https:\/\/actaxlaw.com\/zh-hans\/kaifanggangwei\/#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/actaxlaw.com\/zh-hans\/kaifanggangwei\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/actaxlaw.com\/zh-hans\/kaifanggangwei\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/actaxlaw.com\/zh-hans\/"},{"@type":"ListItem","position":2,"name":"\u5f00\u653e\u5c97\u4f4d"}]},{"@type":"WebSite","@id":"https:\/\/actaxlaw.com\/zh-hans\/#website","url":"https:\/\/actaxlaw.com\/zh-hans\/","name":"Ac Avvocati","description":"Avvocati e Commercialisti","publisher":{"@id":"https:\/\/actaxlaw.com\/zh-hans\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/actaxlaw.com\/zh-hans\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"zh-Hans"},{"@type":"Organization","@id":"https:\/\/actaxlaw.com\/zh-hans\/#organization","name":"Ac Avvocati","url":"https:\/\/actaxlaw.com\/zh-hans\/","logo":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/actaxlaw.com\/zh-hans\/#\/schema\/logo\/image\/","url":"https:\/\/actaxlaw.com\/wp-content\/uploads\/2017\/11\/AC-logo-1.png","contentUrl":"https:\/\/actaxlaw.com\/wp-content\/uploads\/2017\/11\/AC-logo-1.png","width":88,"height":91,"caption":"Ac Avvocati"},"image":{"@id":"https:\/\/actaxlaw.com\/zh-hans\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/actaxlaw.com\/zh-hans\/wp-json\/wp\/v2\/pages\/1773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/actaxlaw.com\/zh-hans\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/actaxlaw.com\/zh-hans\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/actaxlaw.com\/zh-hans\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/actaxlaw.com\/zh-hans\/wp-json\/wp\/v2\/comments?post=1773"}],"version-history":[{"count":0,"href":"https:\/\/actaxlaw.com\/zh-hans\/wp-json\/wp\/v2\/pages\/1773\/revisions"}],"wp:attachment":[{"href":"https:\/\/actaxlaw.com\/zh-hans\/wp-json\/wp\/v2\/media?parent=1773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}